{"id":696,"date":"2023-08-08T14:10:08","date_gmt":"2023-08-08T14:10:08","guid":{"rendered":"https:\/\/ohme.wpengine.com\/ie\/?page_id=696"},"modified":"2024-06-10T14:00:40","modified_gmt":"2024-06-10T14:00:40","slug":"terminos-y-condiciones","status":"publish","type":"legal-policy","link":"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/","title":{"rendered":"Terms &#038; Conditions"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">FACILITAMOS AL USUARIO UN SERVICIO QUE LE PERMITE CONTROLAR Y OPTIMIZAR LA CARGA DE SU VEH\u00cdCULO EL\u00c9CTRICO DE ACUERDO CON LAS PREFERENCIAS Y LOS HORARIOS DE CARGA QUE ESTABLEZCA UTILIZANDO LOS PRODUCTOS OHME. A CONTINUACI\u00d3N, SE ESTABLECEN LOS T\u00c9RMINOS Y CONDICIONES QUE RIGEN EL SUMINISTRO DE TODOS LOS PRODUCTOS OHME Y EL SERVICIO QUE LE PRESTAMOS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AVISO IMPORTANTE:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le aconsejamos que imprima una copia de estos T\u00e9rminos para su referencia en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando lea estos T\u00e9rminos, preste especial atenci\u00f3n a las siguientes condiciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfPor qu\u00e9 son necesarios estos T\u00e9rminos?<\/li>\n\n\n\n<li>Tarifas y cargos<\/li>\n\n\n\n<li>Devoluci\u00f3n de Productos Ohme<\/li>\n\n\n\n<li>Asistencia y contacto<\/li>\n\n\n\n<li>Modificaciones a los presentes T\u00e9rminos<\/li>\n\n\n\n<li>Restricciones al uso de los Productos Ohme<\/li>\n\n\n\n<li>Qu\u00e9 responsabilidad asumimos<\/li>\n\n\n\n<li>Interrupci\u00f3n del Servicio<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">1. Informaci\u00f3n sobre nuestra entidad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.1. Si adquiere alg\u00fan Producto Ohme o tiene su residencia habitual o fiscal en Espa\u00f1a, la contraparte de este acuerdo ser\u00e1 Ohme Operations Ireland Limited, con domicilio social en 74 Penrose Wharf, Penrose Quay, Cork, Rep\u00fablica de Irlanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haremos referencia a la entidad de Ohme correspondiente en cada caso como \u201cOhme\u201d, \u201cnosotros\u201d, \u201cnos\u201d, \u201cnuestro\u201d y sus posibles derivados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Nuestro Contrato<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.1. Los presentes T\u00e9rminos se aplican a cualquier pedido que usted realice para el suministro de Productos Ohme y al uso que usted haga del Servicio (conforme a la definici\u00f3n prevista m\u00e1s abajo). Quedan excluidas cualesquiera otras condiciones impl\u00edcitas por costumbre, h\u00e1bito, pr\u00e1ctica o desarrollo de la actividad comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. \u00bfA qu\u00e9 nos dedicamos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.1. Nuestra misi\u00f3n es facilitar que el usuario ahorre dinero, proteger el medio ambiente y prolongar la vida \u00fatil de la bater\u00eda de su veh\u00edculo el\u00e9ctrico ayud\u00e1ndolo a controlar la duraci\u00f3n y la velocidad de la carga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.2. Para ello, suministramos productos inteligentes de Ohme para veh\u00edculos el\u00e9ctricos (los \u201cProductos Ohme\u201d), que deben utilizarse con nuestra aplicaci\u00f3n software para tel\u00e9fonos m\u00f3viles \u201cOhme \u2013 Intelligent EV charger\u201d y con integraciones con dispositivos como la Skill de Alexa para Ohme (la \u201cAplicaci\u00f3n\u201d) para configurar telem\u00e1ticamente el perfil de carga de la bater\u00eda de su veh\u00edculo el\u00e9ctrico (el \u201cServicio\u201d).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. \u00bfPor qu\u00e9 son necesarios estos T\u00e9rminos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.1. Cuando en los presentes T\u00e9rminos nos referimos a \u201custed\u201d o \u201cel usuario\u201d, hacemos referencia a cualquier persona que adquiera un Producto Ohme y acceda al Servicio o el Sitio Web, o haga uso de ellos, as\u00ed como a cualquier persona que cree una cuenta con nosotros (para m\u00e1s informaci\u00f3n, consulte la secci\u00f3n \u201c\u00bfC\u00f3mo se accede al Servicio?\u201d que aparece m\u00e1s abajo y <a href=\"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\">https:\/\/ohme-ev.com\/es\/terminos-y-condiciones<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.2. Estos T\u00e9rminos tambi\u00e9n rigen el acceso y uso del Sitio Web y la Aplicaci\u00f3n, la adquisici\u00f3n de Productos Ohme y el uso que se haga del Servicio. Junto con los T\u00e9rminos para Usuarios Finales de la Aplicaci\u00f3n (los \u201cT\u00e9rminos de la Aplicaci\u00f3n\u201d, disponibles en <a href=\"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones-moviles\/\">https:\/\/ohme-ev.com\/es\/terminos-y-condiciones-moviles\/<\/a>) y la Pol\u00edtica de Privacidad, conforman el contrato entre las partes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.3. Cuando utilice la Aplicaci\u00f3n para acceder al Servicio, ser\u00e1n aplicables los T\u00e9rminos de la Aplicaci\u00f3n, adem\u00e1s de los presentes T\u00e9rminos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.4. Los T\u00e9rminos de la Aplicaci\u00f3n tambi\u00e9n contienen informaci\u00f3n importante sobre las limitaciones a nuestra responsabilidad en lo que respecta al contenido de terceros y las restricciones sobre el uso que se haga de la Aplicaci\u00f3n. Estas disposiciones tambi\u00e9n son aplicables al uso del Sitio Web. Le aconsejamos que las lea detenidamente antes de utilizar el Sitio Web o la Aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.5. Nuestra Pol\u00edtica de Privacidad (disponible&nbsp;<a href=\"https:\/\/ohme-ev.com\/es\/politica-de-privacidad\/\">https:\/\/ohme-ev.com\/es\/politica-de-privacidad\/<\/a>) explica c\u00f3mo podemos utilizar sus datos personales en relaci\u00f3n con el Sitio Web, el Servicio, la Aplicaci\u00f3n y la adquisici\u00f3n por su parte de los Productos Ohme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. \u00bfC\u00f3mo se accede al Servicio?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.1. Cuando reciba un Producto Ohme, tendr\u00e1 que descargar la Aplicaci\u00f3n y crear una cuenta de usuario (la \u201cCuenta\u201d) para acceder al Servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.2. Debe mantener sus credenciales de acceso a la Cuenta en condiciones de confidencialidad y la responsabilidad de toda actividad que se lleve a cabo a trav\u00e9s de ella ser\u00e1 suya \u00edntegramente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.3. Toda la informaci\u00f3n que facilite a trav\u00e9s de su Cuenta o en la Aplicaci\u00f3n, incluida la informaci\u00f3n de registro de cualquier veh\u00edculo, debe ser correcta en todo momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.4. En caso de saber o sospechar que cualquier otra persona conozca los datos de acceso a su Cuenta, av\u00edsenos lo antes posible escribiendo a <a href=\"mailto:asistencia@ohme-ev.com\">asistencia@ohme-ev.com<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.5. Tendremos acceso a toda la informaci\u00f3n de su Cuenta y la generada al utilizar la Aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.6. Podemos desactivar su Cuenta en cualquier momento si averiguamos que esta se est\u00e1 utilizando de manera contraria a los presentes T\u00e9rminos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. \u00bfC\u00f3mo se usa el Servicio?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.1. Se pueden crear horarios de carga en funci\u00f3n de sus h\u00e1bitos diarios y monitorizar la carga de su veh\u00edculo. Tenga en cuenta que la Aplicaci\u00f3n puede actualizar un perfil de carga autom\u00e1ticamente si considera que el horario que ha elegido el usuario no es practicable dentro del per\u00edodo establecido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.2. Los horarios de carga basados en costes \u00fanicamente se aplicar\u00e1n cuando el usuario utilice una tarifa el\u00e9ctrica sujeta a discriminaci\u00f3n horaria en el punto de carga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.3. El Servicio tambi\u00e9n puede ajustar la carga en funci\u00f3n de las condiciones del sistema el\u00e9ctrico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.4. El Producto Ohme est\u00e1 dise\u00f1ado para funcionar de manera coordinada con las demandas de la red el\u00e9ctrica, de modo que el r\u00e9gimen de carga podr\u00e1 verse limitado durante per\u00edodos breves de tiempo con el fin de facilitar la gesti\u00f3n de la demanda el\u00e9ctrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. Asistencia y contacto<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.1. Si tiene alg\u00fan problema al adquirir el Producto Ohme o al utilizar el Sitio Web, el Servicio o el Producto Ohme, puede ponerse en contacto con nosotros utilizando la funci\u00f3n de chat integrado en la Aplicaci\u00f3n, disponible de 9:00 a 18:00 (GMT), o escribiendo a nuestro equipo de soporte a <a href=\"mailto:asistencia@ohme-ev.com\">asistencia@ohme-ev.com<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.2. Al iniciar sesi\u00f3n en la Aplicaci\u00f3n, podr\u00edamos pedirle que complete breves encuestas, en su caso, para ayudarnos a mejorar su experiencia de usuario y resolver los problemas que surjan con la Aplicaci\u00f3n o el Sitio Web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8. Tarifas y cargos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.1. El precio de nuestro Producto Ohme (IVA incluido) ser\u00e1 el que se indica en la p\u00e1gina del pedido al realizarlo o el que le comuniquemos nosotros o alguno de nuestros socios.&nbsp; Toda informaci\u00f3n sobre precios estar\u00e1 sujeta a posibles cambios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.2. Los costes de conectividad continuada al Sistema Global de Comunicaciones m\u00f3viles (GSM) incluidos en el precio de cualquier cable o cargador de pared adquirido a partir del 1&nbsp;de julio de 2020, inclusive, se indicar\u00e1n en la p\u00e1gina del pedido al realizarlo o se los comunicaremos nosotros o alguno de nuestros socios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.3. En estos momentos, no cobramos ninguna tarifa por descargar la Aplicaci\u00f3n ni por utilizar el Servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.4. No obstante, en el futuro podr\u00edamos optar por introducir alg\u00fan cargo por descargar la Aplicaci\u00f3n o utilizar el Servicio. Siempre le comunicaremos con antelaci\u00f3n cualesquiera cambios en nuestras tarifas y le ofreceremos la posibilidad de decidir si desea seguir utilizando el Servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9. Realizaci\u00f3n de pedidos y pagos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.1. Puede adquirir los Productos Ohme realizando el pedido en nuestro Sitio Web o a trav\u00e9s de uno de nuestros socios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.2. Si va a adquirir un Producto Ohme a trav\u00e9s de nuestro Sitio Web, siga las instrucciones que se muestran en pantalla para realizar el pedido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.3. Nuestro proceso le permite verificar y corregir posibles errores antes de confirmar el pedido. Cada pedido realizado constituye una oferta por la que se presta a adquirir los Productos Ohme en el marco previsto en los presentes T\u00e9rminos. Antes de confirmar el pedido, rev\u00edselo detenidamente. La responsabilidad de garantizar que su pedido est\u00e9 completo y sea correcto recae exclusivamente sobre usted.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.4. Recibir\u00e1 un correo electr\u00f3nico nuestro para confirmar la aceptaci\u00f3n de su pedido, en el que se incluir\u00e1 el n\u00famero de pedido que asignemos a su compra. Si se pone en contacto con nosotros en relaci\u00f3n con alg\u00fan pedido, resultar\u00e1 de gran ayuda que disponga de dicho n\u00famero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.5. Si no podemos aceptar su pedido, le escribiremos un correo electr\u00f3nico para comunic\u00e1rselo y no le cobraremos el Producto Ohme. Entre los motivos por los que podr\u00edamos rechazar su pedido destacan:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.5.1. que no haya existencias del Producto Ohme en cuesti\u00f3n;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.5.2. que se haya producido alguna limitaci\u00f3n imprevista a nuestros recursos que no podamos haber anticipado;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.5.3. que hayamos identificado un error en el precio o la descripci\u00f3n del Producto Ohme,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.5.4. que no podamos cumplir el plazo de entrega que nos ha solicitado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.6. Al facilitarnos una tarjeta de cr\u00e9dito o d\u00e9bito u otro de los m\u00e9todos de pago que aceptemos (como la transferencia bancaria), declara y garantiza que tiene permiso para utilizar dicho m\u00e9todo y nos autoriza (o al tercero que designemos para tramitar los pagos) a practicar el cargo correspondiente al importe total de su pedido en dicho m\u00e9todo de pago (incluidos cualesquiera impuestos o cargos adicionales que correspondan). Si el m\u00e9todo de pago que nos ha facilitado no se puede verificar, no es v\u00e1lido o no resulta aceptable por alg\u00fan otro motivo, podr\u00edamos suspender o cancelar su pedido. Para poder proceder con su pedido, deber\u00e1 resolver cualquier problema que identifiquemos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10. Entrega de los Productos Ohme<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.1. Nuestro objetivo es enviar todos los pedidos en el plazo de 2&nbsp;d\u00edas h\u00e1biles (siempre que haya existencias) desde que procesamos su pedido. Cuando se efect\u00fae el env\u00edo de su pedido, se lo comunicaremos por correo electr\u00f3nico. Asimismo, antes de realizar el pedido, se le informar\u00e1 de cualesquiera gastos de transporte que correspondan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.2. La entrega se considera efectuada cuando los Productos Ohme se han entregado en la direcci\u00f3n de entrega prevista en su pedido. A partir de ese momento, el Producto Ohme pasa a ser responsabilidad suya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.3. No asumiremos ninguna responsabilidad por la entrega tard\u00eda de los Productos Ohme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.4. Usted es propietario de los Productos Ohme una vez que recibamos la totalidad del pago, incluidos los gastos de env\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11. Modificaci\u00f3n de pedidos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.1. No es posible realizar cambios en los pedidos una vez se hayan procesado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.2. Si desea a\u00f1adir art\u00edculos a su pedido, tendr\u00e1 que realizar uno nuevo. Cada pedido tendr\u00e1 sus propios gastos de env\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12. Devoluci\u00f3n de pedidos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.1. Tiene derecho a cambiar de opini\u00f3n y solicitar un reembolso \u00edntegro de los Productos Ohme que adquiera en un plazo de 14&nbsp;d\u00edas desde que los reciba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.2. Si desea cancelar un pedido, puede comunic\u00e1rnoslo por correo electr\u00f3nico (escribiendo a la direcci\u00f3n indicada en los ep\u00edgrafes 5.4 y 7.1) antes de que finalice el per\u00edodo de desistimiento (es decir, en el plazo de 14&nbsp;d\u00edas, inclusive, desde que haya recibido los Productos Ohme). Le enviaremos un correo electr\u00f3nico para confirmar que hemos recibido la cancelaci\u00f3n. Aquellos Productos Ohme que se desee devolver deben encontrarse en el mismo estado en que los recibi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.3. Si desea devolver su pedido porque los Productos Ohme son defectuosos o no se corresponden con la descripci\u00f3n, tiene derecho a su reparaci\u00f3n o sustituci\u00f3n, o bien al reembolso de una parte o de la totalidad de su dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.4. Despu\u00e9s de informarnos de que desea devolver los Productos Ohme, debe devolver aquellos que no desee en el plazo de 14&nbsp;d\u00edas desde la fecha en que nos notificara su decisi\u00f3n, envi\u00e1ndolos a Ohme Operations Ireland Limited, Unit B2, Fota Retail Park, Carrigtwohill, Cork, Rep\u00fablica de Irlanda, T45 W677.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deber\u00e1 correr con los gastos de transporte y ser\u00e1 responsable del Producto Ohme hasta el momento en que lo recibamos.&nbsp; Le recomendamos que utilice un servicio de env\u00edo con seguimiento y seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.5. Cuando hayamos recibido su devoluci\u00f3n, nos pondremos en contacto con usted para acordar los detalles del reembolso o el cambio. Una vez que la devoluci\u00f3n se haya tramitado, le enviaremos un correo electr\u00f3nico de confirmaci\u00f3n. Recibir\u00e1 el reembolso que corresponda en el plazo de 14&nbsp;d\u00edas desde que recibamos los Productos Ohme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.6. Si devuelve los Productos Ohme porque son defectuosos o por alguno de los motivos previstos m\u00e1s arriba, le reembolsaremos el coste b\u00e1sico que nos hubiera abonado por el env\u00edo inicial de los Productos Ohme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.7.&nbsp;&nbsp;&nbsp;&nbsp; Si desea alg\u00fan reemplazo o reembolso, devuelva el Producto Ohme siguiendo el proceso antedicho; le reembolsaremos los gastos de env\u00edo. Usted ser\u00e1 responsable en todo momento de velar por la integridad del Producto Ohme hasta que se nos haya devuelto. Le confirmaremos la recepci\u00f3n mediante correo electr\u00f3nico. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.8.&nbsp;&nbsp;&nbsp;&nbsp; Si desea el reemplazo de alg\u00fan Producto Ohme, trataremos de envi\u00e1rselo en un plazo de 14&nbsp;d\u00edas desde que recibamos el producto devuelto. Si el reemplazo tiene un precio de venta m\u00e1s elevado, nos reservamos el derecho de cobrarle la diferencia entre el precio del Producto Ohme devuelto y el de sustituci\u00f3n. El reemplazo del Producto Ohme tambi\u00e9n estar\u00e1 cubierto por nuestra garant\u00eda de producto. El reemplazo no conlleva una ampliaci\u00f3n del per\u00edodo de garant\u00eda, que se calcular\u00e1 a partir de la fecha de compra inicial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si desea recibir el reembolso de alg\u00fan Producto Ohme defectuoso, trataremos de realizarlo en el plazo de 14&nbsp;d\u00edas desde la recepci\u00f3n.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.9.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; No repararemos, sustituiremos ni reembolsaremos ning\u00fan Producto Ohme defectuoso que se nos devuelva en caso de que ya no est\u00e9 cubierto por la garant\u00eda. Por ejemplo, no aceptaremos la devoluci\u00f3n ni la sustituci\u00f3n de ning\u00fan Producto Ohme cuando este se considere defectuoso debido a da\u00f1os o desperfectos causados por: i)&nbsp;un uso inadecuado, ii)&nbsp;haber estado expuesto a condiciones ambientales inadecuadas para su uso, iii)&nbsp;una instalaci\u00f3n incorrecta por parte de instaladores que no tuvieran nuestra autorizaci\u00f3n expresa, o iv)&nbsp;vandalismo, condiciones clim\u00e1ticas adversas o da\u00f1os en la instalaci\u00f3n el\u00e9ctrica del usuario.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13. El Producto Ohme<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.1. El Producto Ohme se suministra con el convencimiento de que se utilizar\u00e1 de acuerdo con el manual de usuario que lo acompa\u00f1a y que usted deber\u00e1 leer, comprender y cumplir.&nbsp; Asimismo, deber\u00e1 disponer de suficiente cobertura m\u00f3vil (3G\/4G) que permita el uso de las funciones de carga inteligente en su Producto Ohme; en caso contrario, no funcionar\u00e1 correctamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.2. El Producto Ohme se utilizar\u00e1 en pa\u00edses en los que Ohme ejercita su actividad comercial, a saber, Reino&nbsp;Unido, Irlanda, Pa\u00edses Bajos, B\u00e9lgica, Francia, Espa\u00f1a, Italia y Portugal (en su conjunto, los \u201c<strong>Pa\u00edses Pertinentes<\/strong>\u201d y, a t\u00edtulo individual, el \u201c<strong>Pa\u00eds Pertinente<\/strong>\u201d). Ohme podr\u00e1 a\u00f1adir otros pa\u00edses si m\u00e1s adelante expande su actividad a otros territorios, en cuyo caso se ampliar\u00e1 en consecuencia la lista de Pa\u00edses Pertinentes incluida en la presente cl\u00e1usula 13.2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.3. Ofrecemos una garant\u00eda de producto por la cual, desde la recepci\u00f3n del producto y durante un per\u00edodo de 3&nbsp;a\u00f1os en el caso de los cables de carga port\u00e1tiles y los cargadores dom\u00e9sticos adquiridos y suministrados en Espa\u00f1a a partir del 1&nbsp;de&nbsp;enero de 2022, el Producto Ohme:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.3.1. se adecuar\u00e1 a la descripci\u00f3n correspondiente prevista en el Sitio Web en el momento de la compra, y<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.3.2. estar\u00e1 libre de defectos en su dise\u00f1o, materiales y acabados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.4. No asumimos responsabilidad alguna por la vulneraci\u00f3n de la garant\u00eda del producto si:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.4.1. sigue utilizando el Producto Ohme despu\u00e9s de informarnos de que no se ajusta a la descripci\u00f3n o que es defectuoso;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.4.2. altera o repara el Producto Ohme;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.4.3. no tiene suficiente cobertura m\u00f3vil para que el Producto Ohme utilice las funciones de carga inteligente descritas;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.4.4. el defecto se debe al desgaste propio del uso ordinario o a da\u00f1os deliberados, usos negligentes o unas condiciones de almacenamiento o funcionamiento an\u00f3malas, o bien<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.4.5. el Producto Ohme no se corresponde con la descripci\u00f3n o las especificaciones debido a cambios realizados para garantizar que satisface los requisitos legales o reglamentarios aplicables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.5. La garant\u00eda del producto est\u00e1 supeditada a que el comprador cumpla sus obligaciones de pago de conformidad con los t\u00e9rminos acordados. En caso de impago, atraso en la liquidaci\u00f3n de cuotas o cualquier otro incumplimiento de los t\u00e9rminos de pago previstos en el acuerdo de compraventa, la cobertura de la garant\u00eda del cargador dom\u00e9stico quedar\u00e1 anulada una vez que el per\u00edodo de la garant\u00eda del producto haya caducado, seg\u00fan el caso, de acuerdo con los t\u00e9rminos previstos anteriormente, y Ohme se reserva el derecho a denegar a partir de entonces cualesquiera reclamaciones de la garant\u00eda o solicitudes de reparaci\u00f3n o reemplazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">13.6. Los presentes T\u00e9rminos tambi\u00e9n se aplican a los Productos Ohme reparados o reemplazados que nosotros le facilitemos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.&nbsp; Instalaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.1.<strong>&nbsp; <\/strong>Las disposiciones de la presente cl\u00e1usula 14 \u00fanicamente se aplicar\u00e1n cuando le prestemos servicios de instalaci\u00f3n del Producto Ohme,&nbsp; pero no resultar\u00e1n aplicables, y no asumiremos responsabilidad alguna con respecto a la instalaci\u00f3n, si nosotros no ofrecemos dichos servicios de instalaci\u00f3n o cuando la instalaci\u00f3n la lleve a cabo un tercero que no hayamos designado a tal efecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.2. <strong>Contrataci\u00f3n de la instalaci\u00f3n.<\/strong> Podr\u00e1 solicitar la instalaci\u00f3n de su Producto Ohme envi\u00e1ndonos una petici\u00f3n, en el caso de que ofrezcamos servicios de instalaci\u00f3n en su pa\u00eds en ese momento. Una vez que recibamos su solicitud, le enviaremos un cuestionario para que lo cumplimente, en el que usted se compromete a facilitar informaci\u00f3n honesta y precisa. Utilizaremos las respuestas al cuestionario para determinar si se trata de una instalaci\u00f3n \u201cest\u00e1ndar\u201d o \u201cno est\u00e1ndar o personalizada\u201d<s>.<\/s>&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.3. <strong>Costes de la instalaci\u00f3n.<\/strong> En el caso de una instalaci\u00f3n est\u00e1ndar, el coste estar\u00e1 incluido en el precio de adquisici\u00f3n del Producto Ohme o se le notificar\u00e1 en el momento de la compra, y la llevaremos a cabo sin coste adicional para usted. En el caso de una instalaci\u00f3n no est\u00e1ndar, le enviaremos un presupuesto indicando el coste adicional que conllevar\u00eda; una vez aprobado, programaremos la fecha y la hora de la instalaci\u00f3n. En todos los casos, se le confirmar\u00e1 la hora de instalaci\u00f3n por correo electr\u00f3nico.<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.4.<strong>Cancelaci\u00f3n de la instalaci\u00f3n.<\/strong> Podr\u00e1 cancelar la instalaci\u00f3n sin coste alguno hasta 48&nbsp;horas antes de la hora programada. Si la cancela con una antelaci\u00f3n de entre 24 y 48&nbsp;horas, incurrir\u00e1 en un coste equivalente a 50&nbsp;euros m\u00e1s IVA. Si la cancela con menos de 24&nbsp;horas de antelaci\u00f3n, tendr\u00e1 que abonar el 100&nbsp;% de los costes de instalaci\u00f3n. <strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.5.<strong>Requisitos para la instalaci\u00f3n.<\/strong> Durante la instalaci\u00f3n, tendr\u00e1 que estar presente en el emplazamiento usted o una persona de al menos 18&nbsp;a\u00f1os que usted designe a tal fin (la \u201c<strong>Persona Autorizada<\/strong>\u201d), y autoriza a esta \u00faltima a tomar las decisiones necesarias en su nombre en lo que respecta a la instalaci\u00f3n, como la sustituci\u00f3n del Producto Ohme o la ubicaci\u00f3n del cableado.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.6. Deber\u00e1 asegurarse de que el emplazamiento es seguro para la instalaci\u00f3n antes de que esta se lleve a cabo, y declara, garantiza y se compromete a garantizar que se satisfacen todas las leyes en materia de salud y seguridad antes de la llegada de la persona autorizada por Ohme para realizar la instalaci\u00f3n (el \u201c<strong>Instalador<\/strong>\u201d).&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.7. Usted ser\u00e1 responsable de obtener todos los permisos necesarios para la instalaci\u00f3n. En algunos casos, podr\u00edamos pedirle que nos facilite copias de los mismos para nuestra validaci\u00f3n antes de la instalaci\u00f3n. En el marco del proceso de instalaci\u00f3n, podr\u00edamos revisar de manera conjunta, la ruta del cableado y, en el emplazamiento de la instalaci\u00f3n, podr\u00edamos pedirle que firme digitalmente su conformidad con la ruta pactada.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.8. En algunos casos, podr\u00eda ser necesario realizar obras adicionales antes de que pueda instalarse el Producto Ohme, por ejemplo, cuando as\u00ed nos lo notifique, tanto a usted como a nosotros, alg\u00fan gestor de la red de distribuci\u00f3n (GDR). Usted reconoce que estas demoras escapan a nuestro control y que no asumiremos responsabilidad alguna por ninguna p\u00e9rdida que se derive de ellas ni tendremos la obligaci\u00f3n de realizar la instalaci\u00f3n hasta que las obras se hayan completado.&nbsp;&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.9. <strong>Costes posteriores a la instalaci\u00f3n. <\/strong>Cuando ya se haya instalado un Producto Ohme y hagan falta obras adicionales relacionadas con la instalaci\u00f3n, por ejemplo, para desplazar el Producto Ohme (siempre que la garant\u00eda no cubra dichas obras), tendr\u00e1 que correr con los gastos correspondientes, en cuyo caso le facilitaremos un presupuesto antes de su realizaci\u00f3n.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.10. <strong>Interrupci\u00f3n de la instalaci\u00f3n.<\/strong> Si en la hora acordada para la instalaci\u00f3n se deniega el acceso al Instalador, este se ve obligado a esperar sin respuesta o acceso durante 10&nbsp;minutos o m\u00e1s, o si existen motivos para poner en duda la seguridad de la instalaci\u00f3n (incluidas las condiciones de seguridad del emplazamiento o las condiciones clim\u00e1ticas), el Instalador podr\u00e1 interrumpirla, sin que ello conlleve responsabilidad alguna para usted. En el caso de que usted sea responsable de la interrupci\u00f3n de la instalaci\u00f3n, podr\u00edamos exigirle que abone los costes razonables en que se haya incurrido.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.11. <strong>Naturaleza estimada del horario de la instalaci\u00f3n.<\/strong> Usted comprende y acepta que los horarios de la instalaci\u00f3n son \u00fanicamente aproximados y que no asumiremos responsabilidad alguna por cualesquiera p\u00e9rdidas que usted o cualquier otra persona sufran en el caso de que el Instalador no llegue al lugar de la instalaci\u00f3n a la hora acordada.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.12. <strong>Diligencia y cuidado razonables.<\/strong> Llevaremos a cabo la instalaci\u00f3n o nos aseguraremos de que el Instalador la efect\u00faa con la diligencia y el cuidado razonables.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">14.13. <strong>Garant\u00eda.<\/strong> Proporcionamos una garant\u00eda de 3&nbsp;a\u00f1os con respecto a las obras de instalaci\u00f3n que llevemos a cabo nosotros o que se realicen en nuestro nombre, siempre y cuando no se hayan ejecutado obras adicionales (sin nuestra autorizaci\u00f3n) desde la instalaci\u00f3n original.&nbsp;<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15. Modificaciones a los presentes T\u00e9rminos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">15.1. Es posible que tengamos que modificar estos T\u00e9rminos, seg\u00fan corresponda en cada momento. Los cambios que hagamos se publicar\u00e1n en esta p\u00e1gina y, cuando sean sustanciales, se los comunicaremos envi\u00e1ndole un correo electr\u00f3nico con los detalles o notific\u00e1ndoselo la pr\u00f3xima vez que utilice el Sitio Web o la Aplicaci\u00f3n, en cuyo caso podr\u00edamos pedirle que los acepte expresamente de nuevo. Aseg\u00farese de leer los cambios a los T\u00e9rminos antes de seguir utilizando el Sitio Web, el Servicio o la Aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16. Cambios en el Sitio Web<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16.1. El Sitio Web se pone a su disposici\u00f3n sin coste alguno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16.2. No garantizamos que el Sitio Web ni su contenido est\u00e9n disponibles siempre o de manera ininterrumpida. Por motivos comerciales u operativos, el Sitio Web podr\u00eda suspenderse o retirarse y su disponibilidad podr\u00eda restringirse en parte o en su totalidad, en cuyo caso trataremos de comunic\u00e1rselo con una antelaci\u00f3n razonable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16.3. Usted es responsable de garantizar que cualquier persona que acceda al Sitio Web a trav\u00e9s de su conexi\u00f3n a internet conozca y cumpla estos T\u00e9rminos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17. Titularidad de los derechos y uso de los datos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17.1. Ohme es titular (o licenciatario) de todos los derechos de propiedad intelectual e industrial asociados con el Producto Ohme (incluido el software integrado en \u00e9l) y con el Sitio Web (incluido el material que en \u00e9l se publique).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17.2. Asimismo, somos titulares de todos los derechos de propiedad intelectual e industrial derivados de cualesquiera materiales que se generen a partir del uso que usted haga de la Aplicaci\u00f3n y el Servicio, y que nos cede autom\u00e1ticamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17.3.&nbsp; Somos los propietarios de todos los datos o la informaci\u00f3n que se generen en relaci\u00f3n con el uso que usted haga del Sitio Web, la Aplicaci\u00f3n, el Producto Ohme y nuestros Servicios, y tenemos derecho a hacer uso de ellos. En el caso de que dicha informaci\u00f3n contenga datos personales, \u00fanicamente los utilizaremos de acuerdo con lo previsto en nuestra Pol\u00edtica de Privacidad (disponible en <a href=\"https:\/\/ohme-ev.com\/es\/politica-de-privacidad\/\">https:\/\/ohme-ev.com\/es\/politica-de-privacidad\/<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18. C\u00f3mo puede utilizar nuestro Sitio Web<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.1. Se permite imprimir copias y descargar extractos de cualquier p\u00e1gina de nuestro Sitio Web para su uso personal, as\u00ed como dirigir la atenci\u00f3n de otras personas de su organizaci\u00f3n hacia el contenido publicado en el mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.2. No obstante, no deber\u00e1 modificar las copias, ya sean impresas o digitales, de ning\u00fan material que haya impreso o descargado de nuestro Sitio Web en modo alguno. Del mismo modo, tampoco podr\u00e1 utilizar ilustraciones, fotograf\u00edas, v\u00eddeos, secuencias de audio ni recursos gr\u00e1ficos sin el texto que los acompa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.3. En todo momento, deber\u00e1 reconocerse nuestra autor\u00eda del contenido del Sitio Web (o la de cualquier otra persona identificada como tal).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.4. Si imprime, copia o descarga cualquier parte del Sitio Web o la Aplicaci\u00f3n de manera contraria a estos T\u00e9rminos, su derecho a usar el Sitio Web, la Aplicaci\u00f3n y el Servicio se extinguir\u00e1n de inmediato, y usted deber\u00e1, a su elecci\u00f3n, restituir o destruir toda copia que haya realizado de los materiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">18.5. Aunque el Sitio Web y el Servicio son accesibles en todo el mundo, \u00fanicamente se pueden utilizar con nuestros Productos Ohme, que deben utilizarse en un veh\u00edculo ubicado en uno de los Pa\u00edses Pertinentes. Es posible que algunas o todas las funciones del Sitio Web o el Servicio no funcionen si accede a ellas desde un territorio ajeno a los Pa\u00edses Pertinentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19. Virus<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19.1. No garantizamos que el Sitio Web, la Aplicaci\u00f3n o su uso del Servicio sean seguros o se encuentren desprovistos de errores o virus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19.2. Usted es responsable de configurar sus tecnolog\u00edas de la informaci\u00f3n, programas de ordenador y plataformas para acceder al Sitio Web, y debe procurarse su propio software antivirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19.3. Usted se abstendr\u00e1 de introducir virus, troyanos, gusanos, bombas l\u00f3gicas u otros materiales maliciosos o tecnol\u00f3gicamente da\u00f1inos en el Sitio Web o la Aplicaci\u00f3n. Adem\u00e1s, no est\u00e1 permitido tratar de obtener acceso no autorizado al Sitio Web, el servidor en el que este se aloja ni ning\u00fan otro servidor, ordenador o base de datos conectados al Sitio Web, ni la vinculaci\u00f3n del mismo a trav\u00e9s de un ataque de denegaci\u00f3n de servicio o ataque distribuido de denegaci\u00f3n de servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">19.4. Cualquier persona involucrada en las actividades antedichas quedar\u00e1 vetada para utilizar el Sitio Web, la Aplicaci\u00f3n o el Servicio, y podr\u00eda considerarse que ha cometido un delito en el marco del C\u00f3digo Penal espa\u00f1ol. Si tales actividades pasan a ser de nuestro conocimiento, las denunciaremos a las autoridades policiales competentes y nos veremos en la obligaci\u00f3n de revelar la identidad de las personas involucradas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20. Foro y comunicaci\u00f3n con otros usuarios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20.1. Podremos ofrecer funciones que permitan el intercambio de informaci\u00f3n a trav\u00e9s de un foro integrado dentro de la Aplicaci\u00f3n (el \u201cForo\u201d). Cualquier informaci\u00f3n personal que usted muestre o facilite a trav\u00e9s de \u00e9l pasar\u00e1 a ser de dominio p\u00fablico; no nos hacemos responsables de ning\u00fan dato que usted decida hacer p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20.2. Podremos eliminar en cualquier momento aquellas comunicaciones que consideremos de car\u00e1cter obsceno, difamatorio u hostigador, dentro de lo razonable. Si publica contenido que, a nuestro parecer, sea de esta naturaleza, ser\u00e1 responsable de cualquier p\u00e9rdida que usted o nosotros podamos sufrir en consecuencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20.3. Asimismo, cuando utilice el Foro, debe tener en cuenta que las comunicaciones virtuales nunca son completamente privadas o seguras. Cualquier mensaje o informaci\u00f3n que env\u00ede a trav\u00e9s del Foro podr\u00eda ser le\u00eddo o interceptado por otras personas, incluso si se le informa de que una comunicaci\u00f3n en particular est\u00e1 cifrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20.4. Si decide comunicarse o reunirse con cualquier otro usuario intercambiando sus direcciones de correo electr\u00f3nico o postal, n\u00fameros de tel\u00e9fono u otros datos de contacto a trav\u00e9s del Foro, lo har\u00e1 a su cuenta y riesgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">20.5. Ninguno de los datos que facilite a trav\u00e9s del Foro tendr\u00e1 la consideraci\u00f3n de confidencial. Usted seguir\u00e1 siendo el titular de los derechos correspondientes al contenido que facilite, pero nos concede licencia no exclusiva para utilizarlo sin limitaci\u00f3n alguna. No asumiremos la responsabilidad de abonar ning\u00fan pago de c\u00e1nones ni ninguna otra retribuci\u00f3n en lo relativo a dicho contenido. Podremos utilizar y transmitir libremente dicho contenido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21. Restricciones al uso del Producto Ohme<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.1. Usted se abstendr\u00e1 de utilizar el Producto Ohme, el Sitio Web, la Aplicaci\u00f3n (de acuerdo con los T\u00e9rminos y Condiciones de la Aplicaci\u00f3n) y el Servicio con fines comerciales, il\u00edcitos o incompatibles con estos T\u00e9rminos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.2. No garantizamos que:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.2.1. el Producto Ohme sea compatible con todos los veh\u00edculos;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.2.2. el Producto Ohme cargue su veh\u00edculo conforme al horario de carga, ni<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.2.3. el firmware, software o las actualizaciones de la Aplicaci\u00f3n o las funciones de dichas actualizaciones est\u00e9n disponibles para todos los Productos Ohme comercializados o instalados con anterioridad a la fecha de lanzamiento de dichas actualizaciones, o que sean compatibles con ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.3. Del mismo modo, se abstendr\u00e1 de:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.3.1. manipular o desmontar cualquier parte del Producto Ohme;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.3.2. retirar o manipular la tarjeta SIM facilitada con el Producto Ohme, utilizar una tarjeta SIM alternativa que no le hayamos facilitado nosotros o usar la que le facilitemos en otro dispositivo, o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.3.3. utilizar el Producto Ohme si sabe o sospecha que podr\u00eda estar da\u00f1ado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.4. Acepta que todas las reparaciones de los Productos Ohme las realizaremos nosotros y que debe informarnos cuanto antes de cualquier problema que tenga con el Producto Ohme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21.5. Si incumple alguna parte de estos T\u00e9rminos, podr\u00edamos emprender acciones legales contra usted.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22. Qu\u00e9 responsabilidad asumimos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.1. Si bien usted recibe este Servicio a t\u00edtulo gratuito, no asumiremos responsabilidad alguna por ninguna p\u00e9rdida que sufra debido al uso de nuestro Servicio, salvo cuando se nos atribuya dicha responsabilidad por ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.2. Salvo cuando se nos atribuya por ley la responsabilidad de todas las p\u00e9rdidas que usted pudiera sufrir como resultado del uso del Producto Ohme, nuestra responsabilidad total a tenor de los presentes T\u00e9rminos queda limitada al importe que haya abonado por el Producto Ohme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3. No somos responsables de las p\u00e9rdidas, costes o da\u00f1os y perjuicios causados por:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.1. el uso, sea o no indebido, que usted haga de los Productos Ohme, el Sitio Web, la Aplicaci\u00f3n o el Servicio, salvo cuando se deban a negligencia por nuestra parte;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.2. la configuraci\u00f3n de los horarios de carga;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.3. las limitaciones a la carga, los ajustes de la aplicaci\u00f3n con respecto a sus horarios de carga o los ajustes de su horario de carga que realicemos en funci\u00f3n de los requisitos del sistema de distribuci\u00f3n el\u00e9ctrica;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.4. la configuraci\u00f3n incorrecta de alg\u00fan dispositivo o su uso para acceder al Servicio, incluida la configuraci\u00f3n de la zona horaria;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.5. cualquier aver\u00eda o fallo de su veh\u00edculo;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.6. cualquier ca\u00edda del suministro o de la distribuci\u00f3n el\u00e9ctrica mientras hay un Producto Ohme cargando su veh\u00edculo, o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.3.7. aquellos productos o servicios de terceros que escapen a nuestro control y a los que recurramos para prestar una parte del Servicio, incluidos errores de instalaci\u00f3n o da\u00f1os materiales causados por la instalaci\u00f3n (por ejemplo, las paredes o la instalaci\u00f3n el\u00e9ctrica).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">22.4. No renunciamos ni limitamos en modo alguno nuestra responsabilidad en aquellos casos en que resulte il\u00edcito hacerlo. Esto incluye la responsabilidad por fallecimiento o por da\u00f1os corporales que puedan producirse por negligencia nuestra; por fraudes o declaraciones fraudulentas; por la vulneraci\u00f3n de sus derechos legales con respecto a los productos \u2014incluido el derecho a recibir productos que se correspondan con su descripci\u00f3n y con la informaci\u00f3n que le facilitemos, que sean de calidad satisfactoria y que se suministren con la diligencia y el cuidado razonables\u2014, y por aquellos productos que sean defectuosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">23. Interrupci\u00f3n del Servicio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">23.1. Estos T\u00e9rminos permanecer\u00e1n con plena vigencia y efecto mientras usted acceda o utilice el Producto Ohme o el Servicio, o hasta que cualquiera de las partes pongamos fin a dicho acceso o uso por alg\u00fan motivo previsto en estos T\u00e9rminos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">23.2. Podr\u00edamos suspender o cerrar su Cuenta y extinguir su derecho a usar el Sitio Web, la Aplicaci\u00f3n o el Servicio si los utiliza, o utiliza alguno de los Productos Ohme, de modo contrario a los presentes T\u00e9rminos o lleva a cabo actividades il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">24. Ausencia de derechos a favor de terceros<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los presentes T\u00e9rminos son vinculantes entre las partes: usted y nosotros, de modo que ninguna otra persona tendr\u00e1 derecho a hacer valer ninguna de las condiciones previstas en estos T\u00e9rminos (a excepci\u00f3n de aquellas personas a quienes usted ceda su garant\u00eda). Ni usted ni nosotros precisaremos de la aprobaci\u00f3n de ninguna otra persona para resolver el contrato o practicar cambio alguno en estos T\u00e9rminos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">25. Legislaci\u00f3n aplicable y jurisdicci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">25.1. Al adquirir o utilizar Productos, Servicios o el Sitio Web, usted acepta estos T\u00e9rminos, con las modificaciones posteriores que proceda introducir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">25.2. Si reside en Espa\u00f1a, estos T\u00e9rminos se regir\u00e1n e interpretar\u00e1n de acuerdo con el Derecho espa\u00f1ol, y cualesquiera conflictos o pretensiones que puedan surgir de ellos se someter\u00e1n exclusivamente a los \u00f3rganos jurisdiccionales correspondientes a su domicilio en Espa\u00f1a. En caso de conflicto, cuando usted act\u00fae en calidad de consumidor, deber\u00e1 tratar de resolverlo de manera amistosa envi\u00e1ndonos una reclamaci\u00f3n por escrito a <a href=\"mailto:asistencia@ohme-ev.com\">asistencia@ohme-ev.com<\/a>. Si no se alcanza una soluci\u00f3n amistosa en el plazo de 60&nbsp;d\u00edas desde la presentaci\u00f3n de la reclamaci\u00f3n, tendr\u00e1 derecho a solicitar la resoluci\u00f3n amistosa del conflicto a trav\u00e9s de la plataforma de resoluci\u00f3n de litigios online, a la que puede acceder en <a href=\"http:\/\/ec.europa.eu\/consumers\/odr\/\">http:\/\/ec.europa.eu\/consumers\/odr\/<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00daltima actualizaci\u00f3n: 2 de octubre de 2023<\/p>\n","protected":false},"template":"","class_list":["post-696","legal-policy","type-legal-policy","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>T\u00e9rminos y Condiciones - Ohme EV Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms &amp; Conditions\" \/>\n<meta property=\"og:description\" content=\"T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Ohme EV Espa\u00f1a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OhmeEV\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T14:00:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ohmeev\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"24 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/terminos-y-condiciones\\\/\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/terminos-y-condiciones\\\/\",\"name\":\"T\u00e9rminos y Condiciones - Ohme EV Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/#website\"},\"datePublished\":\"2023-08-08T14:10:08+00:00\",\"dateModified\":\"2024-06-10T14:00:40+00:00\",\"description\":\"T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/terminos-y-condiciones\\\/#breadcrumb\"},\"inLanguage\":\"es-es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ohme-ev.com\\\/es\\\/terminos-y-condiciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/terminos-y-condiciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legal Policies\",\"item\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/legal-policy\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Terms &#038; Conditions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/\",\"name\":\"Ohme EV Espa\u00f1a\",\"description\":\"Ohme - Cargando El Ma\u00f1ana\",\"publisher\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/#organization\",\"name\":\"Ohme EV Espa\u00f1a\",\"alternateName\":\"Ohme\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-es\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/05\\\/Vector-1-e1747753854161.webp\",\"contentUrl\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/05\\\/Vector-1-e1747753854161.webp\",\"width\":86,\"height\":81,\"caption\":\"Ohme EV Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OhmeEV\\\/\",\"https:\\\/\\\/x.com\\\/ohmeev\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y Condiciones - Ohme EV Espa\u00f1a","description":"T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Terms & Conditions","og_description":"T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios","og_url":"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/","og_site_name":"Ohme EV Espa\u00f1a","article_publisher":"https:\/\/www.facebook.com\/OhmeEV\/","article_modified_time":"2024-06-10T14:00:40+00:00","twitter_card":"summary_large_image","twitter_site":"@ohmeev","twitter_misc":{"Est. reading time":"24 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/","url":"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/","name":"T\u00e9rminos y Condiciones - Ohme EV Espa\u00f1a","isPartOf":{"@id":"https:\/\/ohme-ev.com\/es\/#website"},"datePublished":"2023-08-08T14:10:08+00:00","dateModified":"2024-06-10T14:00:40+00:00","description":"T\u00e9rminos y Condiciones del Sitio Web de Ohme para el Suministro de Productos y la Prestaci\u00f3n de Servicios","breadcrumb":{"@id":"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es-es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ohme-ev.com\/es\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ohme-ev.com\/es\/"},{"@type":"ListItem","position":2,"name":"Legal Policies","item":"https:\/\/ohme-ev.com\/es\/legal-policy\/"},{"@type":"ListItem","position":3,"name":"Terms &#038; Conditions"}]},{"@type":"WebSite","@id":"https:\/\/ohme-ev.com\/es\/#website","url":"https:\/\/ohme-ev.com\/es\/","name":"Ohme EV Espa\u00f1a","description":"Ohme - Cargando El Ma\u00f1ana","publisher":{"@id":"https:\/\/ohme-ev.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ohme-ev.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-es"},{"@type":"Organization","@id":"https:\/\/ohme-ev.com\/es\/#organization","name":"Ohme EV Espa\u00f1a","alternateName":"Ohme","url":"https:\/\/ohme-ev.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-es","@id":"https:\/\/ohme-ev.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ohme-ev.com\/es\/wp-content\/uploads\/sites\/17\/2025\/05\/Vector-1-e1747753854161.webp","contentUrl":"https:\/\/ohme-ev.com\/es\/wp-content\/uploads\/sites\/17\/2025\/05\/Vector-1-e1747753854161.webp","width":86,"height":81,"caption":"Ohme EV Espa\u00f1a"},"image":{"@id":"https:\/\/ohme-ev.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OhmeEV\/","https:\/\/x.com\/ohmeev"]}]}},"_links":{"self":[{"href":"https:\/\/ohme-ev.com\/es\/wp-json\/wp\/v2\/legal-policy\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ohme-ev.com\/es\/wp-json\/wp\/v2\/legal-policy"}],"about":[{"href":"https:\/\/ohme-ev.com\/es\/wp-json\/wp\/v2\/types\/legal-policy"}],"wp:attachment":[{"href":"https:\/\/ohme-ev.com\/es\/wp-json\/wp\/v2\/media?parent=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}