{"id":2650,"date":"2024-08-21T16:07:57","date_gmt":"2024-08-21T16:07:57","guid":{"rendered":"https:\/\/ohme-ev.com\/de\/?post_type=guides&#038;p=2650"},"modified":"2024-10-29T09:59:32","modified_gmt":"2024-10-29T09:59:32","slug":"glossar-rund-ums-laden-ihres-e-autos","status":"publish","type":"guides","link":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/","title":{"rendered":"Glossar rund um&#8217;s Laden Ihres E-Autos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1868\" height=\"1054\" src=\"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg\" alt=\"Person using an EV charger\" class=\"wp-image-1333\" srcset=\"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg 1868w, https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK-300x169.jpg 300w, https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK-1024x578.jpg 1024w, https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK-768x433.jpg 768w, https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK-1536x867.jpg 1536w, https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK-798x450.jpg 798w\" sizes=\"auto, (max-width: 1868px) 100vw, 1868px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Neu im Bereich der Elektrofahrzeuge und unsicher, wovon alle reden? Wir haben Ihnen ein handliches Glossar des gesamten EV-Vokabulars zusammengestellt \u2013 einfach erkl\u00e4rt!<\/p>\n\n\n\n<div class=\"wp-block-group blog-layout\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">AC (Wechselstrom)<\/h3>\n\n\n\n<p>Wechselstrom. Diese Stromart wird f\u00fcr Heim-EV-Ladeger\u00e4te verwendet. Der Strom flie\u00dft \u00fcber das Ladeger\u00e4t des Fahrzeugs, bevor er in der Batterie gespeichert werden kann.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">API (Programmierschnittstelle)<\/h3>\n\n\n\n<p>Eine API (Application Programming Interface) erm\u00f6glicht den Zugriff auf Informationen \u00fcber Ihr Auto \u00fcber die Smartphone-App Ihres Herstellers. Wenn Sie Ihre Login-Daten in der Ohme-App hinterlegen, kann Ohme auf den aktuellen Ladezustand Ihres Autos zugreifen. Dies wird verwendet, um zu berechnen, wie viel Ladung Sie ben\u00f6tigen. Derzeit sind wir mit folgenden APIs integriert: Audi, BMW, Hyundai, Jaguar, Kia, MINI, Nissan, Renault, SKODA, Tesla, Volkswagen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Batterie-Elektrofahrzeug (BEV)<\/h3>\n\n\n\n<p>Ein batteriebetriebenes Fahrzeug, das aufgeladen wird, wenn es an das Stromnetz angeschlossen ist.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Batteriekapazit\u00e4t<\/h3>\n\n\n\n<p>Dies ist die Menge an Energie, die eine Batterie speichern kann (und wird oft in die erreichbare Reichweite umgerechnet). Diese Kapazit\u00e4t nimmt im Laufe der Zeit ab, da die Batterie altert.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ladegeschwindigkeit<\/h3>\n\n\n\n<p>Manchmal auch als Ladegeschwindigkeit bezeichnet, beschreibt dies, wie schnell Strom von Ihrem Elektrofahrzeug aufgenommen wird (oder aufgenommen werden kann).\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ladeplan<\/h3>\n\n\n\n<p>Dies sind Ihre Standardladepr\u00e4ferenzen. Sie k\u00f6nnen diese im Bereich &#8220;My Charger&#8221; der Ohme-App erstellen, damit Ihr Auto bis zu Ihrer gew\u00fcnschten Abfahrtszeit auf den gew\u00fcnschten Ladezustand aufgeladen ist.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CSS (Combined Charging System)<\/h3>\n\n\n\n<p>Dies sind Ihre Standardladepr\u00e4ferenzen. Sie k\u00f6nnen diese im Bereich &#8220;My Charger&#8221; der Ohme-App erstellen, damit Ihr Auto bis zu Ihrer gew\u00fcnschten Abfahrtszeit auf den gew\u00fcnschten Ladezustand aufgeladen ist.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Steckertyp<\/h3>\n\n\n\n<p>Ladeger\u00e4te haben entweder fest installierte Kabel (siehe \u201eTethered\u201c) oder Sie m\u00fcssen Ihr eigenes Kabel anschlie\u00dfen (siehe \u201eUn-tethered\u201c). Die Enden dieser Kabel k\u00f6nnen verschiedene Stecker haben. Die meisten Elektrofahrzeuge, die nach 2018 hergestellt wurden, ben\u00f6tigen einen Typ-2-Stecker.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">CPO<\/h3>\n\n\n\n<p>Betreiber von Ladestationen. Diese Unternehmen besitzen und betreiben \u00f6ffentliche Ladestationen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">DC (Gleichstrom)<\/h3>\n\n\n\n<p>Gleichstrom. Diese Stromart wird f\u00fcr \u00f6ffentliche Schnellladeger\u00e4te verwendet. Das Laden mit Gleichstrom ist schneller als mit Wechselstrom, da der Strom direkt in die Batterie flie\u00dft, ohne das Ladeger\u00e4t des Fahrzeugs passieren zu m\u00fcssen<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Degradation<\/h3>\n\n\n\n<p>EV-Batterien bestehen aus Lithium-Ionen (wie Laptop- und Handy-Akkus). Sie funktionieren durch die Bewegung von Lithium-Ionen. Jedes Mal, wenn Sie die Batterie vollst\u00e4ndig aufladen und entladen, wird die Reaktion, die diese Bewegung in den Zellen verursacht, weniger effizient. Das bedeutet, dass die Batterie im Laufe der Zeit weniger Ladung halten kann und sich schneller entl\u00e4dt.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Brennstroffzellenfahrzeug (FCEV)<\/h3>\n\n\n\n<p>Ein Elektrofahrzeug, das mit Energie betrieben wird, die durch eine chemische Reaktion zwischen Wasserstoff und Sauerstoff in der Luft erzeugt wird.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ICE (Verbennungsmotor)<\/h3>\n\n\n\n<p>Dies sind herk\u00f6mmliche Benzin- und Dieselfahrzeuge.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">kW (Kilowatt)<\/h3>\n\n\n\n<p>Dies ist eine Leistungseinheit. In den Spezifikationen Ihres Elektrofahrzeugs sehen Sie, dass Ihr Onboard-Ladeger\u00e4t eine Ladegeschwindigkeit in kW aufweist. Dies gibt an, wie schnell Ihr Elektrofahrzeug mit einem Wechselstromladeger\u00e4t geladen werden kann.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">kWh (Kilowattstunde)<\/h3>\n\n\n\n<p>Dies ist eine Energieeinheit. In den Spezifikationen Ihres Elektrofahrzeugs sehen Sie, dass Ihre Batteriekapazit\u00e4t in kWh angegeben ist. Dies zeigt an, wie viel Energie Ihre Batterie speichern kann. Vielleicht kennen Sie Meilen pro Gallone als Ma\u00dfstab, um zu berechnen, wie weit Sie mit einem vollen Tank kommen. Bei einem Elektrofahrzeug denken Sie stattdessen an Meilen pro kWh. Weitere Informationen hier.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Max Charge<\/h3>\n\n\n\n<p>Eine Funktion in der Ohme-App, die alle Ladepl\u00e4ne und intelligenten Funktionen vor\u00fcbergehend deaktiviert, um Ihr Auto mit voller Leistung so weit wie m\u00f6glich aufzuladen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Plug-in-Hybrid-Elektrofahrzeug<\/h3>\n\n\n\n<p>Ein Benzin- oder Dieselfahrzeug, das auch \u00fcber eine kleine Batterie verf\u00fcgt, die mit Netzstrom aufgeladen werden muss.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Neustart\u00a0<\/h3>\n\n\n\n<p>Der Neustart eines Ladeger\u00e4ts bedeutet, das Ger\u00e4t durch Aus- und Einschalten am Hauptstromkreis zur\u00fcckzusetzen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reichweite<\/h3>\n\n\n\n<p>Dies beschreibt, wie viele Kilometer Sie mit Ihrem Elektrofahrzeug fahren k\u00f6nnen, ohne es aufladen zu m\u00fcssen. Die Reichweite kann je nach Fahrstil, Wetterbedingungen und Zustand der EV-Batterie variieren.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reichweitenangst<\/h3>\n\n\n\n<p>Reichweitenangst beschreibt die Sorge, dass der Akku leer ist, bevor Sie Ihr Ziel erreichen. Die meisten Elektrofahrzeuge schaffen mit einer Ladung zwischen 100 und 300 Meilen. Obwohl es die h\u00e4ufigste Angst unter Elektrofahrzeugfahrern ist, ist sie meist unbegr\u00fcndet.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reichweitenverl\u00e4ngerndes EV (REx)\u00a0<\/h3>\n\n\n\n<p>Eine Art Hybrid-Elektrofahrzeug mit einem kleinen Benzingenerator, der die Batterie aufl\u00e4dt, wenn die Reichweite ersch\u00f6pft ist, und so eine weitere Fahrt erm\u00f6glicht.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rekuperationsbremse<\/h3>\n\n\n\n<p>Fahrzeuge mit Rekuperationsbremsen k\u00f6nnen die beim Bremsen verbrauchte Energie zur\u00fcckgewinnen und wieder in ihren Batterien speichern. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Smart Charging<\/h3>\n\n\n\n<p>Ein intelligentes Ladesystem, das das Laden \u00fcber Datenverbindungen optimiert. Ohme-Ladeger\u00e4te berechnen die besten Ladezeiten basierend auf Ihrem aktuellen Stromtarif und den Netzbedingungen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SoC (Ladezustand)<\/h3>\n\n\n\n<p>Der Ladezustand gibt an, wie viel Energie sich in Ihrer Batterie befindet. Dieser Wert wird als Prozentsatz in Ihrem Auto oder der Auto-App angezeigt.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tethered<\/h3>\n\n\n\n<p>Ein Tethered-Ladeger\u00e4t, wie das Ohme Home Pro, hat ein fest eingebautes Ladekabel. Um Ihr Elektrofahrzeug zu laden, m\u00fcssen Sie es nur abwickeln und in das Fahrzeug einstecken.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trickle Charge<\/h3>\n\n\n\n<p>Ein Trickle Charge bezieht sich auf eine sehr langsame Ladegeschwindigkeit. Die niedrigste Geschwindigkeit, mit der ein Auto sicher geladen werden kann, betr\u00e4gt 6A \/ 1,44kW.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zeitabh\u00e4ngiger Tarif<\/h3>\n\n\n\n<p>Ein zeitabh\u00e4ngiger Tarif bietet zu bestimmten Tageszeiten, wenn weniger Menschen Strom verbrauchen, g\u00fcnstigere Preise. Dies ermutigt Kunden, Strom zu Zeiten mit geringerer Nachfrage zu nutzen und hilft so, das Stromnetz auszugleichen. Diese g\u00fcnstigeren Zeiten sind typischerweise nachts, weshalb diese Tarife bei Elektrofahrzeugfahrern beliebt sind, die ihr Auto w\u00e4hrend des Schlafens aufladen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zweckabh\u00e4ngiger Tarif<\/h3>\n\n\n\n<p>Ein zweckabh\u00e4ngiger Tarif bietet g\u00fcnstigere Strompreise, wenn er f\u00fcr bestimmte Zwecke verwendet wird, wie das Laden eines Elektrofahrzeugs. Diese Tarife sind bei Elektrofahrzeugfahrern beliebt, da sie das Aufladen zu g\u00fcnstigeren Tarifen erm\u00f6glichen.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ULEZ (Ultra Low Emission Zone)<\/h3>\n\n\n\n<p>Eine Zone, in der Fahrer ohne ein emissionsarmes oder emissionsfreies Fahrzeug eine t\u00e4gliche Geb\u00fchr zahlen m\u00fcssen, wenn sie ohne ein konformes Fahrzeug in die Zone einfahren.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">V2G (Vehicle to Grid)<\/h3>\n\n\n\n<p>Diese Technologie erm\u00f6glicht es Fahrern, ihre Batterien aufzuladen und dann Energie zur\u00fcck ins Stromnetz zu speisen, oft verbunden mit einer finanziellen Belohnung. Diese Technologie befindet sich noch in der fr\u00fchen Entwicklungsphase und wird von Ohme-Ladeger\u00e4ten nicht unterst\u00fctzt.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">V2H (Vehicle to Home)<\/h3>\n\n\n\n<p>Diese Technologie erm\u00f6glicht es Fahrern, ihre Batterien aufzuladen und diese gespeicherte Energie dann zur Stromversorgung ihres Zuhauses zu nutzen. Diese Technologie befindet sich noch in der fr\u00fchen Entwicklungsphase und wird von Ohme-Ladeger\u00e4ten nicht unterst\u00fctzt.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">WLTP (Worldwide Harmonized Light Vehicles Test Procedure)<\/h3>\n\n\n\n<p>Ein Test, der entwickelt wurde, um eine realistischere Einsch\u00e4tzung der Reichweite und Kraftstoffeffizienz eines Autos zu geben.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zero Emission<\/h3>\n\n\n\n<p>Dies kann alles sein (ein Auto, ein Unternehmen, eine Energiequelle), das keine Treibhausgase ausst\u00f6\u00dft.\u00a0\u00a0<\/p>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\r\n\t\t\t<div id=\"daexthefu-container\"\r\n\t\t\t\tclass=\"daexthefu-container daexthefu-layout-side-by-side daexthefu-alignment-left\"\r\n\t\t\t\tdata-post-id=\"2650\">\r\n\r\n\t\t\t\t<div class=\"daexthefu-feedback\">\r\n\t\t\t\t\t<div class=\"daexthefu-text\">\r\n\t\t\t\t\t\t<h3 class=\"daexthefu-title\">Was this helpful?<\/h3>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"daexthefu-buttons-container\">\r\n\t\t\t\t\t\t<div class=\"daexthefu-buttons\">\r\n\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-yes daexthefu-button daexthefu-button-type-text\" data-value=\"1\">\r\n\t\t\t\t<div class=\"daexthefu-button-text\">Yes<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t\r\n\t\t\t<div class=\"daexthefu-no daexthefu-button daexthefu-button-type-text\" data-value=\"0\">\r\n\t\t\t\t<div class=\"daexthefu-button-text\">No<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-comment\">\r\n\t\t\t\t\t<div class=\"daexthefu-comment-top-container\">\r\n\t\t\t\t\t\t<label id=\"daexthefu-comment-label\" class=\"daexthefu-comment-label\"><\/label>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-container\">\r\n\t\t\t\t\t\t\t\t<div id=\"daexthefu-comment-character-counter-number\"\r\n\t\t\t\t\t\t\t\t\tclass=\"daexthefu-comment-character-counter-number\"><\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"daexthefu-comment-character-counter-text\"><\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<textarea id=\"daexthefu-comment-textarea\" class=\"daexthefu-comment-textarea\"\r\n\t\t\t\t\t\t\t\tplaceholder=\"Type your message\"\r\n\t\t\t\t\t\t\t\tmaxlength=\"\r\n\t\t\t\t\t\t\t\t400\t\t\t\t\t\t\t\t\t\"><\/textarea>\r\n\t\t\t\t\t<div class=\"daexthefu-comment-buttons-container\">\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-submit daexthefu-button\">Submit<\/button>\r\n\t\t\t\t\t\t<button class=\"daexthefu-comment-cancel daexthefu-button\">Cancel<\/button>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<div class=\"daexthefu-successful-submission-text\">Thanks for your feedback!<\/div>\r\n\r\n\t\t\t<\/div>\r\n\r\n\t\t\t","protected":false},"excerpt":{"rendered":"<p>Neu im Bereich der Elektrofahrzeuge und unsicher, wovon alle reden? Wir haben Ihnen ein handliches Glossar des gesamten EV-Vokabulars zusammengestellt \u2013 einfach erkl\u00e4rt! AC (Wechselstrom) Wechselstrom. Diese Stromart wird f\u00fcr Heim-EV-Ladeger\u00e4te verwendet. Der Strom flie\u00dft \u00fcber das Ladeger\u00e4t des Fahrzeugs, bevor er in der Batterie gespeichert werden kann.\u00a0 API (Programmierschnittstelle) Eine API (Application Programming Interface) [&hellip;]<\/p>\n","protected":false},"featured_media":1333,"template":"","meta":{"_acf_changed":false,"_helpful_status":1},"categories":[15],"tags":[130],"class_list":["post-2650","guides","type-guides","status-publish","has-post-thumbnail","hentry","category-bevor-es-losgeht","tag-glossar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Glossar rund um&#039;s Laden Ihres E-Autos - Ohme EV Deutschland<\/title>\n<meta name=\"description\" content=\"New to electric vehicles and not sure what everybody&#039;s talking about? Here&#039;s all of the EV jargon in plain English.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glossar rund um&#039;s Laden Ihres E-Autos\" \/>\n<meta property=\"og:description\" content=\"New to electric vehicles and not sure what everybody&#039;s talking about? Here&#039;s all of the EV jargon in plain English.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ohme EV Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OhmeEV\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T09:59:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1868\" \/>\n\t<meta property=\"og:image:height\" content=\"1054\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ohmeev\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/\",\"name\":\"Glossar rund um's Laden Ihres E-Autos - Ohme EV Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/08\\\/Support_ePod_smile_UK.jpg\",\"datePublished\":\"2024-08-21T16:07:57+00:00\",\"dateModified\":\"2024-10-29T09:59:32+00:00\",\"description\":\"New to electric vehicles and not sure what everybody's talking about? Here's all of the EV jargon in plain English.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/#breadcrumb\"},\"inLanguage\":\"de-de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-de\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/08\\\/Support_ePod_smile_UK.jpg\",\"contentUrl\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/08\\\/Support_ePod_smile_UK.jpg\",\"width\":1868,\"height\":1054,\"caption\":\"Person using an EV charger\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/glossar-rund-ums-laden-ihres-e-autos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Support guides\",\"item\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/support\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glossar rund um&#8217;s Laden Ihres E-Autos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/\",\"name\":\"Ohme EV Deutschland\",\"description\":\"Ohme - EV Smart Charging Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/#organization\",\"name\":\"Ohme EV\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-de\",\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/07\\\/Ohme-blue-logo.webp\",\"contentUrl\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/07\\\/Ohme-blue-logo.webp\",\"width\":393,\"height\":192,\"caption\":\"Ohme EV\"},\"image\":{\"@id\":\"https:\\\/\\\/ohme-ev.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OhmeEV\\\/\",\"https:\\\/\\\/x.com\\\/ohmeev\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/19177772\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Glossar rund um's Laden Ihres E-Autos - Ohme EV Deutschland","description":"New to electric vehicles and not sure what everybody's talking about? Here's all of the EV jargon in plain English.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/","og_locale":"de_DE","og_type":"article","og_title":"Glossar rund um's Laden Ihres E-Autos","og_description":"New to electric vehicles and not sure what everybody's talking about? Here's all of the EV jargon in plain English.","og_url":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/","og_site_name":"Ohme EV Deutschland","article_publisher":"https:\/\/www.facebook.com\/OhmeEV\/","article_modified_time":"2024-10-29T09:59:32+00:00","og_image":[{"width":1868,"height":1054,"url":"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ohmeev","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/","url":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/","name":"Glossar rund um's Laden Ihres E-Autos - Ohme EV Deutschland","isPartOf":{"@id":"https:\/\/ohme-ev.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/#primaryimage"},"image":{"@id":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/#primaryimage"},"thumbnailUrl":"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg","datePublished":"2024-08-21T16:07:57+00:00","dateModified":"2024-10-29T09:59:32+00:00","description":"New to electric vehicles and not sure what everybody's talking about? Here's all of the EV jargon in plain English.","breadcrumb":{"@id":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/#breadcrumb"},"inLanguage":"de-de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/"]}]},{"@type":"ImageObject","inLanguage":"de-de","@id":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/#primaryimage","url":"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg","contentUrl":"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2023\/08\/Support_ePod_smile_UK.jpg","width":1868,"height":1054,"caption":"Person using an EV charger"},{"@type":"BreadcrumbList","@id":"https:\/\/ohme-ev.com\/de\/support\/glossar-rund-ums-laden-ihres-e-autos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ohme-ev.com\/de\/"},{"@type":"ListItem","position":2,"name":"Support guides","item":"https:\/\/ohme-ev.com\/de\/support\/"},{"@type":"ListItem","position":3,"name":"Glossar rund um&#8217;s Laden Ihres E-Autos"}]},{"@type":"WebSite","@id":"https:\/\/ohme-ev.com\/de\/#website","url":"https:\/\/ohme-ev.com\/de\/","name":"Ohme EV Deutschland","description":"Ohme - EV Smart Charging Solutions","publisher":{"@id":"https:\/\/ohme-ev.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ohme-ev.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-de"},{"@type":"Organization","@id":"https:\/\/ohme-ev.com\/de\/#organization","name":"Ohme EV","url":"https:\/\/ohme-ev.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-de","@id":"https:\/\/ohme-ev.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2025\/07\/Ohme-blue-logo.webp","contentUrl":"https:\/\/ohme-ev.com\/de\/wp-content\/uploads\/sites\/23\/2025\/07\/Ohme-blue-logo.webp","width":393,"height":192,"caption":"Ohme EV"},"image":{"@id":"https:\/\/ohme-ev.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OhmeEV\/","https:\/\/x.com\/ohmeev","https:\/\/www.linkedin.com\/company\/19177772"]}]}},"_links":{"self":[{"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/guides\/2650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/guides"}],"about":[{"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/types\/guides"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/media\/1333"}],"wp:attachment":[{"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/media?parent=2650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/categories?post=2650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ohme-ev.com\/de\/wp-json\/wp\/v2\/tags?post=2650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}